{"id":26,"date":"2021-03-29T08:31:21","date_gmt":"2021-03-29T08:31:21","guid":{"rendered":"https:\/\/xn--llorenseguiarquitecte-63b.com\/?page_id=207"},"modified":"2025-08-27T15:05:10","modified_gmt":"2025-08-27T15:05:10","slug":"noticias-arquitectos-menorca","status":"publish","type":"page","link":"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/noticias-arquitectos-menorca\/","title":{"rendered":"Bloguer"},"content":{"rendered":"<div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"bm-builder clearfix\"><div id=\"\" class=\"module col-12 module-id-1686069495769\" data-module-col=\"12\"><div class=\"module-inside grid-inside\" style=\"--top-mod: 0px;--bottom-mod: 0px;--top-mod-m:0px;--bottom-mod-m:0px;\"><div class=\"container-masonry ux-portfolio-3col  ux-portfolio-full  ux-ratio-43 filter-left\" data-ratio=\"0.75\" data-col=\"3\" data-found=\"61\" data-number=\"100\" data-mod=\"grid\"><div class=\"masonry-list grid-list clearfix grid-list-1686069495769  grid-text-center   masonry-auto\"  data-unique=\"1686069495769\" data-source=\"post\"><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"6166\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--6166\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitecto-menorca-diseno-de-viviendas-unifamiliares-en-menorca\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitecto-menorca-diseno-de-viviendas-unifamiliares-en-menorca\/\" title=\"ARQUITECTO MENORCA. Dise\u00f1o de viviendas unifamiliares en Menorca.\" class=\"grid-item-tit-a\" rel=\" \">ARQUITECTO MENORCA. Dise\u00f1o de viviendas unifamiliares en Menorca.<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">juin 12, 2025<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 42.769230769231%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1998\/08\/Foto-2-vivienda-Rafa-y-Raquel-650x278.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1998\/08\/Foto-2-vivienda-Rafa-y-Raquel-arnold-standard-thumb-650x278.png 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1998\/08\/Foto-2-vivienda-Rafa-y-Raquel-300x128.png 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1998\/08\/Foto-2-vivienda-Rafa-y-Raquel-1024x438.png 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1998\/08\/Foto-2-vivienda-Rafa-y-Raquel-768x329.png 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1998\/08\/Foto-2-vivienda-Rafa-y-Raquel-1536x657.png 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1998\/08\/Foto-2-vivienda-Rafa-y-Raquel-350x150.png 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1998\/08\/Foto-2-vivienda-Rafa-y-Raquel-arnold-standard-thumb-medium-1000x428.png 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1998\/08\/Foto-2-vivienda-Rafa-y-Raquel.png 1835w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"ARQUITECTO MENORCA. Dise\u00f1o de viviendas unifamiliares en Menorca.\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"6168\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--6168\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitecto-menorca-obra-nueva-en-menorca-diseno-y-eficiencia-energetica\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitecto-menorca-obra-nueva-en-menorca-diseno-y-eficiencia-energetica\/\" title=\"ARQUITECTO MENORCA. Obra nueva en Menorca: dise\u00f1o y eficiencia energ\u00e9tica.\" class=\"grid-item-tit-a\" rel=\" \">ARQUITECTO MENORCA. Obra nueva en Menorca: dise\u00f1o y eficiencia energ\u00e9tica.<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">juin 12, 2025<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 99.750623441397%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/edificio-22-viviendas-web.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/edificio-22-viviendas-web.png 401w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/edificio-22-viviendas-web-300x300.png 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/edificio-22-viviendas-web-150x150.png 150w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/edificio-22-viviendas-web-350x349.png 350w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 401px) 100vw, 401px\" alt=\"ARQUITECTO MENORCA. Obra nueva en Menorca: dise\u00f1o y eficiencia energ\u00e9tica.\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"6171\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--6171\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitecto-menorca-arquitectura-menorquina-tradicion-y-modernidadarquitecto-menorca-arquitectura-menorquina-tradicion-y-modernidad\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitecto-menorca-arquitectura-menorquina-tradicion-y-modernidadarquitecto-menorca-arquitectura-menorquina-tradicion-y-modernidad\/\" title=\"ARQUITECTO MENORCA. Arquitectura sostenible y bioclim\u00e1tica en Menorca\" class=\"grid-item-tit-a\" rel=\" \">ARQUITECTO MENORCA. Arquitectura sostenible y bioclim\u00e1tica en Menorca<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">juin 12, 2025<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 39.538461538462%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/SEgui-Triay-arquitecte-_Panormica-21-3-1-650x257.jpg\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/SEgui-Triay-arquitecte-_Panormica-21-3-1-arnold-standard-thumb-650x257.jpg 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/SEgui-Triay-arquitecte-_Panormica-21-3-1-300x118.jpg 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/SEgui-Triay-arquitecte-_Panormica-21-3-1-1024x404.jpg 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/SEgui-Triay-arquitecte-_Panormica-21-3-1-768x303.jpg 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/SEgui-Triay-arquitecte-_Panormica-21-3-1-1536x607.jpg 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/SEgui-Triay-arquitecte-_Panormica-21-3-1-350x138.jpg 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/SEgui-Triay-arquitecte-_Panormica-21-3-1-arnold-standard-thumb-medium-1000x395.jpg 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/SEgui-Triay-arquitecte-_Panormica-21-3-1.jpg 1899w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"ARQUITECTO MENORCA. Arquitectura sostenible y bioclim\u00e1tica en Menorca\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"6176\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--6176\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitecto-menorca-arquitectura-menorquina-tradicion-y-modernidadarquitecto-menorca-arquitectura-menorquina-tradicion-y-modernidad-2\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitecto-menorca-arquitectura-menorquina-tradicion-y-modernidadarquitecto-menorca-arquitectura-menorquina-tradicion-y-modernidad-2\/\" title=\"ARQUITECTO MENORCA. Arquitectura menorquina: tradici\u00f3n y modernidad\" class=\"grid-item-tit-a\" rel=\" \">ARQUITECTO MENORCA. Arquitectura menorquina: tradici\u00f3n y modernidad<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">juin 12, 2025<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 42.769230769231%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1998\/08\/Foto-10-Vivienda-Rafa-y-Raquel-650x278.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1998\/08\/Foto-10-Vivienda-Rafa-y-Raquel-arnold-standard-thumb-650x278.png 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1998\/08\/Foto-10-Vivienda-Rafa-y-Raquel-300x128.png 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1998\/08\/Foto-10-Vivienda-Rafa-y-Raquel-1024x438.png 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1998\/08\/Foto-10-Vivienda-Rafa-y-Raquel-768x329.png 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1998\/08\/Foto-10-Vivienda-Rafa-y-Raquel-1536x657.png 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1998\/08\/Foto-10-Vivienda-Rafa-y-Raquel-350x150.png 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1998\/08\/Foto-10-Vivienda-Rafa-y-Raquel-arnold-standard-thumb-medium-1000x428.png 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1998\/08\/Foto-10-Vivienda-Rafa-y-Raquel.png 1835w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"ARQUITECTO MENORCA. Arquitectura menorquina: tradici\u00f3n y modernidad\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"6161\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--6161\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitecto-menorca-2\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitecto-menorca-2\/\" title=\"ARQUITECTO MENORCA\" class=\"grid-item-tit-a\" rel=\" \">ARQUITECTO MENORCA<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">juin 12, 2025<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 42.769230769231%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/06\/Rehabilitacion-fachada-Casa-Vivo-2-650x278.jpg\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/06\/Rehabilitacion-fachada-Casa-Vivo-2-arnold-standard-thumb-650x278.jpg 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/06\/Rehabilitacion-fachada-Casa-Vivo-2-300x128.jpg 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/06\/Rehabilitacion-fachada-Casa-Vivo-2-1024x438.jpg 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/06\/Rehabilitacion-fachada-Casa-Vivo-2-768x329.jpg 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/06\/Rehabilitacion-fachada-Casa-Vivo-2-1536x657.jpg 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/06\/Rehabilitacion-fachada-Casa-Vivo-2-350x150.jpg 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/06\/Rehabilitacion-fachada-Casa-Vivo-2-arnold-standard-thumb-medium-1000x428.jpg 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/06\/Rehabilitacion-fachada-Casa-Vivo-2.jpg 1835w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"ARQUITECTO MENORCA\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"6108\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--6108\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitecto-menorca-viviendas-que-respetan-el-entorno-natural-de-menorca\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitecto-menorca-viviendas-que-respetan-el-entorno-natural-de-menorca\/\" title=\"ARQUITECTO MENORCA. Viviendas que respetan el entorno natural de Menorca\" class=\"grid-item-tit-a\" rel=\" \">ARQUITECTO MENORCA. Viviendas que respetan el entorno natural de Menorca<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">octobre 23, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 35.230769230769%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Concurso-36-viv-Can-Ribes-Mallorca.-lorenzo-segui-Triay.-Menorca-650x229.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Concurso-36-viv-Can-Ribes-Mallorca.-lorenzo-segui-Triay.-Menorca-arnold-standard-thumb-650x229.png 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Concurso-36-viv-Can-Ribes-Mallorca.-lorenzo-segui-Triay.-Menorca-300x106.png 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Concurso-36-viv-Can-Ribes-Mallorca.-lorenzo-segui-Triay.-Menorca-1024x361.png 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Concurso-36-viv-Can-Ribes-Mallorca.-lorenzo-segui-Triay.-Menorca-768x271.png 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Concurso-36-viv-Can-Ribes-Mallorca.-lorenzo-segui-Triay.-Menorca-350x123.png 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Concurso-36-viv-Can-Ribes-Mallorca.-lorenzo-segui-Triay.-Menorca-arnold-standard-thumb-medium-1000x353.png 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Concurso-36-viv-Can-Ribes-Mallorca.-lorenzo-segui-Triay.-Menorca.png 1500w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"ARQUITECTO MENORCA. Viviendas que respetan el entorno natural de Menorca\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"6106\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--6106\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitecto-menorca-soluciones-innovadoras\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitecto-menorca-soluciones-innovadoras\/\" title=\"ARQUITECTO MENORCA. SOLUCIONES INNOVADORAS\" class=\"grid-item-tit-a\" rel=\" \">ARQUITECTO MENORCA. SOLUCIONES INNOVADORAS<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">octobre 23, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 42.769230769231%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/3-7-1-650x278.jpg\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/3-7-1-arnold-standard-thumb-650x278.jpg 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/3-7-1-300x128.jpg 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/3-7-1-1024x438.jpg 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/3-7-1-768x328.jpg 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/3-7-1-1536x657.jpg 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/3-7-1-350x150.jpg 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/3-7-1-arnold-standard-thumb-medium-1000x428.jpg 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/3-7-1.jpg 1836w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"ARQUITECTO MENORCA. SOLUCIONES INNOVADORAS\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"6103\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--6103\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitecto-menorca-diseno-de-viviendas\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitecto-menorca-diseno-de-viviendas\/\" title=\"ARQUITECTO MENORCA. DISE\u00d1O DE VIVIENDAS.\" class=\"grid-item-tit-a\" rel=\" \">ARQUITECTO MENORCA. DISE\u00d1O DE VIVIENDAS.<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">octobre 23, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 42.769230769231%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/29-adosados-3-650x278.jpg\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/29-adosados-3-arnold-standard-thumb-650x278.jpg 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/29-adosados-3-300x128.jpg 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/29-adosados-3-1024x438.jpg 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/29-adosados-3-768x328.jpg 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/29-adosados-3-1536x657.jpg 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/29-adosados-3-350x150.jpg 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/29-adosados-3-arnold-standard-thumb-medium-1000x428.jpg 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/29-adosados-3.jpg 1836w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"ARQUITECTO MENORCA. DISE\u00d1O DE VIVIENDAS.\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"6083\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--6083\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitecto-menorca-4\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitecto-menorca-4\/\" title=\"ARQUITECTO MENORCA\" class=\"grid-item-tit-a\" rel=\" \">ARQUITECTO MENORCA<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">septembre 19, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 42.769230769231%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/29-adosados-4-650x278.jpg\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/29-adosados-4-arnold-standard-thumb-650x278.jpg 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/29-adosados-4-300x128.jpg 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/29-adosados-4-1024x438.jpg 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/29-adosados-4-768x328.jpg 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/29-adosados-4-1536x657.jpg 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/29-adosados-4-350x150.jpg 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/29-adosados-4-arnold-standard-thumb-medium-1000x428.jpg 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/29-adosados-4.jpg 1836w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"ARQUITECTO MENORCA\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"6066\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--6066\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitectos-de-menorca-estetica-tradicional\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitectos-de-menorca-estetica-tradicional\/\" title=\"ARQUITECTOS DE MENORCA. EST\u00c9TICA TRADICIONAL\" class=\"grid-item-tit-a\" rel=\" \">ARQUITECTOS DE MENORCA. EST\u00c9TICA TRADICIONAL<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">septembre 19, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 74.461538461538%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca-650x484.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca-arnold-standard-thumb-650x484.png 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca-300x224.png 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca-1024x763.png 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca-768x572.png 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca-350x261.png 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca-arnold-standard-thumb-medium-1000x745.png 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca.png 1500w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"ARQUITECTOS DE MENORCA. EST\u00c9TICA TRADICIONAL\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"6067\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--6067\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/architectes-de-minorque-larchitecture-unifamiliale-a-minorque\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/architectes-de-minorque-larchitecture-unifamiliale-a-minorque\/\" title=\"ARCHITECTES DE MINORQUE. L&#8217;architecture unifamiliale \u00e0 Minorque.\" class=\"grid-item-tit-a\" rel=\" \">ARCHITECTES DE MINORQUE. L&#8217;architecture unifamiliale \u00e0 Minorque.<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">septembre 19, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 100.2%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/Rehabilitacion-fachada-Casa-Vivo-1-2.jpg\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/Rehabilitacion-fachada-Casa-Vivo-1-2.jpg 500w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/Rehabilitacion-fachada-Casa-Vivo-1-2-300x300.jpg 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/Rehabilitacion-fachada-Casa-Vivo-1-2-150x150.jpg 150w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/Rehabilitacion-fachada-Casa-Vivo-1-2-350x351.jpg 350w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 500px) 100vw, 500px\" alt=\"ARCHITECTES DE MINORQUE. L&#8217;architecture unifamiliale \u00e0 Minorque.\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"6068\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--6068\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/architectes-de-minorque-10\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/architectes-de-minorque-10\/\" title=\"ARCHITECTES DE MINORQUE\" class=\"grid-item-tit-a\" rel=\" \">ARCHITECTES DE MINORQUE<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">septembre 19, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 119.84615384615%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-12-1-650x779.jpg\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-12-1-arnold-standard-thumb-650x779.jpg 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-12-1-250x300.jpg 250w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-12-1-854x1024.jpg 854w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-12-1-768x921.jpg 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-12-1-1281x1536.jpg 1281w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-12-1-1708x2048.jpg 1708w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-12-1-350x420.jpg 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-12-1-arnold-standard-thumb-medium-1000x1199.jpg 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-12-1.jpg 1900w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"ARCHITECTES DE MINORQUE\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"6069\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--6069\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/architectes-de-minorque-9\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/architectes-de-minorque-9\/\" title=\"ARCHITECTES DE MINORQUE\" class=\"grid-item-tit-a\" rel=\" \">ARCHITECTES DE MINORQUE<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">septembre 19, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 42.769230769231%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/bloque-c-002-650x278.jpg\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/bloque-c-002-arnold-standard-thumb-650x278.jpg 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/bloque-c-002-300x128.jpg 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/bloque-c-002-1024x438.jpg 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/bloque-c-002-768x328.jpg 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/bloque-c-002-1536x657.jpg 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/bloque-c-002-350x150.jpg 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/bloque-c-002-arnold-standard-thumb-medium-1000x428.jpg 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/bloque-c-002.jpg 1836w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"ARCHITECTES DE MINORQUE\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"6070\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--6070\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/architectes-de-minorque-larchitecture-minorquine\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/architectes-de-minorque-larchitecture-minorquine\/\" title=\"ARCHITECTES DE MINORQUE. L&#8217;architecture minorquine\" class=\"grid-item-tit-a\" rel=\" \">ARCHITECTES DE MINORQUE. L&#8217;architecture minorquine<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">septembre 19, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 39.538461538462%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/SEgui-Triay-arquitecte-_Panormica-18-3-650x257.jpg\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/SEgui-Triay-arquitecte-_Panormica-18-3-arnold-standard-thumb-650x257.jpg 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/SEgui-Triay-arquitecte-_Panormica-18-3-300x118.jpg 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/SEgui-Triay-arquitecte-_Panormica-18-3-1024x404.jpg 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/SEgui-Triay-arquitecte-_Panormica-18-3-768x303.jpg 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/SEgui-Triay-arquitecte-_Panormica-18-3-1536x607.jpg 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/SEgui-Triay-arquitecte-_Panormica-18-3-350x138.jpg 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/SEgui-Triay-arquitecte-_Panormica-18-3-arnold-standard-thumb-medium-1000x395.jpg 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/SEgui-Triay-arquitecte-_Panormica-18-3.jpg 1899w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"ARCHITECTES DE MINORQUE. L&#8217;architecture minorquine\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"6071\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--6071\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitectos-de-menorca-10\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitectos-de-menorca-10\/\" title=\"ARQUITECTOS DE MENORCA\" class=\"grid-item-tit-a\" rel=\" \">ARQUITECTOS DE MENORCA<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">septembre 19, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 151.53846153846%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-UNIFAMILIAR.-LORENZO-SEGUI-TRIAY-1-650x985.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-UNIFAMILIAR.-LORENZO-SEGUI-TRIAY-1-arnold-standard-thumb-650x985.png 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-UNIFAMILIAR.-LORENZO-SEGUI-TRIAY-1-198x300.png 198w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-UNIFAMILIAR.-LORENZO-SEGUI-TRIAY-1-676x1024.png 676w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-UNIFAMILIAR.-LORENZO-SEGUI-TRIAY-1-768x1164.png 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-UNIFAMILIAR.-LORENZO-SEGUI-TRIAY-1-1014x1536.png 1014w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-UNIFAMILIAR.-LORENZO-SEGUI-TRIAY-1-1352x2048.png 1352w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-UNIFAMILIAR.-LORENZO-SEGUI-TRIAY-1-8x12.png 8w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-UNIFAMILIAR.-LORENZO-SEGUI-TRIAY-1-350x530.png 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-UNIFAMILIAR.-LORENZO-SEGUI-TRIAY-1-arnold-standard-thumb-medium-1000x1515.png 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-UNIFAMILIAR.-LORENZO-SEGUI-TRIAY-1.png 1500w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"ARQUITECTOS DE MENORCA\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"6072\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--6072\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitectos-de-menorca-arquitectura-rural\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitectos-de-menorca-arquitectura-rural\/\" title=\"ARQUITECTOS DE MENORCA. ARQUITECTURA RURAL\" class=\"grid-item-tit-a\" rel=\" \">ARQUITECTOS DE MENORCA. ARQUITECTURA RURAL<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">septembre 19, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 52.615384615385%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/Foto-1-Reforma-casa-Calle-Infanta-Mao-1-6-1-1-1-2-2-2-1-650x342.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/Foto-1-Reforma-casa-Calle-Infanta-Mao-1-6-1-1-1-2-2-2-1-arnold-standard-thumb-650x342.png 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/Foto-1-Reforma-casa-Calle-Infanta-Mao-1-6-1-1-1-2-2-2-1-300x158.png 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/Foto-1-Reforma-casa-Calle-Infanta-Mao-1-6-1-1-1-2-2-2-1-1024x539.png 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/Foto-1-Reforma-casa-Calle-Infanta-Mao-1-6-1-1-1-2-2-2-1-768x404.png 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/Foto-1-Reforma-casa-Calle-Infanta-Mao-1-6-1-1-1-2-2-2-1-1536x808.png 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/Foto-1-Reforma-casa-Calle-Infanta-Mao-1-6-1-1-1-2-2-2-1-350x184.png 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/Foto-1-Reforma-casa-Calle-Infanta-Mao-1-6-1-1-1-2-2-2-1-arnold-standard-thumb-medium-1000x526.png 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/Foto-1-Reforma-casa-Calle-Infanta-Mao-1-6-1-1-1-2-2-2-1.png 1900w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"ARQUITECTOS DE MENORCA. ARQUITECTURA RURAL\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"6073\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--6073\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitectos-de-menorca-9\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitectos-de-menorca-9\/\" title=\"ARQUITECTOS DE MENORCA\" class=\"grid-item-tit-a\" rel=\" \">ARQUITECTOS DE MENORCA<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">septembre 19, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 99.750623441397%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/24-vivendes3-copia-1.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/24-vivendes3-copia-1.png 401w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/24-vivendes3-copia-1-300x300.png 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/24-vivendes3-copia-1-150x150.png 150w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/24-vivendes3-copia-1-350x349.png 350w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 401px) 100vw, 401px\" alt=\"ARQUITECTOS DE MENORCA\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5940\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5940\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/etude-darchitecture-a-minorque\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/etude-darchitecture-a-minorque\/\" title=\"\u00c9tude d&#8217;architecture \u00e0 Minorque\" class=\"grid-item-tit-a\" rel=\" \">\u00c9tude d&#8217;architecture \u00e0 Minorque<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 75.076923076923%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-10-1-650x488.jpg\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-10-1-arnold-standard-thumb-650x488.jpg 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-10-1-300x225.jpg 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-10-1-1024x768.jpg 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-10-1-768x576.jpg 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-10-1-1536x1152.jpg 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-10-1-350x263.jpg 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-10-1-arnold-thumb-43-medium-1000x750.jpg 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-10-1.jpg 1900w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"\u00c9tude d&#8217;architecture \u00e0 Minorque\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"6111\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--6111\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/atelier-darchitecture-de-minorque-6-2\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/atelier-darchitecture-de-minorque-6-2\/\" title=\"Atelier d&#8217;architecture de Minorque\" class=\"grid-item-tit-a\" rel=\" \">Atelier d&#8217;architecture de Minorque<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 42.769230769231%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1981\/08\/Foto-9-Concurso-36-viv-Can-Ribes-Mallorca-650x278.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1981\/08\/Foto-9-Concurso-36-viv-Can-Ribes-Mallorca-arnold-standard-thumb-650x278.png 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1981\/08\/Foto-9-Concurso-36-viv-Can-Ribes-Mallorca-300x128.png 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1981\/08\/Foto-9-Concurso-36-viv-Can-Ribes-Mallorca-1024x438.png 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1981\/08\/Foto-9-Concurso-36-viv-Can-Ribes-Mallorca-768x329.png 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1981\/08\/Foto-9-Concurso-36-viv-Can-Ribes-Mallorca-1536x657.png 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1981\/08\/Foto-9-Concurso-36-viv-Can-Ribes-Mallorca-350x150.png 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1981\/08\/Foto-9-Concurso-36-viv-Can-Ribes-Mallorca-arnold-standard-thumb-medium-1000x428.png 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1981\/08\/Foto-9-Concurso-36-viv-Can-Ribes-Mallorca.png 1835w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Atelier d&#8217;architecture de Minorque\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"6114\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--6114\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/etude-darchitecture-a-minorque-2\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/etude-darchitecture-a-minorque-2\/\" title=\"\u00c9tude d&#8217;architecture \u00e0 Minorque\" class=\"grid-item-tit-a\" rel=\" \">\u00c9tude d&#8217;architecture \u00e0 Minorque<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 74.461538461538%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca-650x484.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca-arnold-standard-thumb-650x484.png 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca-300x224.png 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca-1024x763.png 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca-768x572.png 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca-350x261.png 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca-arnold-standard-thumb-medium-1000x745.png 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca.png 1500w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"\u00c9tude d&#8217;architecture \u00e0 Minorque\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"6117\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--6117\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/etude-darchitecture-a-minorque-3\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/etude-darchitecture-a-minorque-3\/\" title=\"\u00c9tude d&#8217;architecture \u00e0 Minorque\" class=\"grid-item-tit-a\" rel=\" \">\u00c9tude d&#8217;architecture \u00e0 Minorque<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 119.84615384615%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-12-1-650x779.jpg\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-12-1-arnold-standard-thumb-650x779.jpg 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-12-1-250x300.jpg 250w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-12-1-854x1024.jpg 854w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-12-1-768x921.jpg 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-12-1-1281x1536.jpg 1281w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-12-1-1708x2048.jpg 1708w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-12-1-350x420.jpg 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-12-1-arnold-standard-thumb-medium-1000x1199.jpg 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-12-1.jpg 1900w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"\u00c9tude d&#8217;architecture \u00e0 Minorque\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"6120\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--6120\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/etude-darchitecture-a-minorque-4\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/etude-darchitecture-a-minorque-4\/\" title=\"\u00c9tude d&#8217;architecture \u00e0 Minorque\" class=\"grid-item-tit-a\" rel=\" \">\u00c9tude d&#8217;architecture \u00e0 Minorque<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 75.076923076923%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-Casa-Julie-Catala.-lorenzo-segui-Triay.-Menorca-650x488.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-Casa-Julie-Catala.-lorenzo-segui-Triay.-Menorca-arnold-standard-thumb-650x488.png 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-Casa-Julie-Catala.-lorenzo-segui-Triay.-Menorca-300x225.png 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-Casa-Julie-Catala.-lorenzo-segui-Triay.-Menorca-1024x768.png 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-Casa-Julie-Catala.-lorenzo-segui-Triay.-Menorca-768x576.png 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-Casa-Julie-Catala.-lorenzo-segui-Triay.-Menorca-350x263.png 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-Casa-Julie-Catala.-lorenzo-segui-Triay.-Menorca-arnold-thumb-43-medium-1000x750.png 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-Casa-Julie-Catala.-lorenzo-segui-Triay.-Menorca.png 1500w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"\u00c9tude d&#8217;architecture \u00e0 Minorque\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5955\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5955\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/estudio-arquitectura-menorca-5\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/estudio-arquitectura-menorca-5\/\" title=\"Estudio arquitectura Menorca. Un color para un acceso de la casa en Menorca.\" class=\"grid-item-tit-a\" rel=\" \">Estudio arquitectura Menorca. Un color para un acceso de la casa en Menorca.<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 39.538461538462%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/SEgui-Triay-arquitecte-_Panormica-19-3-1-1-650x257.jpg\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/SEgui-Triay-arquitecte-_Panormica-19-3-1-1-arnold-standard-thumb-650x257.jpg 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/SEgui-Triay-arquitecte-_Panormica-19-3-1-1-300x118.jpg 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/SEgui-Triay-arquitecte-_Panormica-19-3-1-1-1024x404.jpg 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/SEgui-Triay-arquitecte-_Panormica-19-3-1-1-768x303.jpg 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/SEgui-Triay-arquitecte-_Panormica-19-3-1-1-1536x607.jpg 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/SEgui-Triay-arquitecte-_Panormica-19-3-1-1-350x138.jpg 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/SEgui-Triay-arquitecte-_Panormica-19-3-1-1-arnold-standard-thumb-medium-1000x395.jpg 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/SEgui-Triay-arquitecte-_Panormica-19-3-1-1.jpg 1899w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Estudio arquitectura Menorca. Un color para un acceso de la casa en Menorca.\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5971\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5971\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/architectes-de-minorque\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/architectes-de-minorque\/\" title=\"Architectes de Minorque. La conception d&#8217;une maison.\" class=\"grid-item-tit-a\" rel=\" \">Architectes de Minorque. La conception d&#8217;une maison.<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 75.076923076923%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-Casa-Julie-Catala.-lorenzo-segui-Triay.-Menorca-650x488.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-Casa-Julie-Catala.-lorenzo-segui-Triay.-Menorca-arnold-standard-thumb-650x488.png 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-Casa-Julie-Catala.-lorenzo-segui-Triay.-Menorca-300x225.png 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-Casa-Julie-Catala.-lorenzo-segui-Triay.-Menorca-1024x768.png 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-Casa-Julie-Catala.-lorenzo-segui-Triay.-Menorca-768x576.png 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-Casa-Julie-Catala.-lorenzo-segui-Triay.-Menorca-350x263.png 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-Casa-Julie-Catala.-lorenzo-segui-Triay.-Menorca-arnold-thumb-43-medium-1000x750.png 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-Casa-Julie-Catala.-lorenzo-segui-Triay.-Menorca.png 1500w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Architectes de Minorque. La conception d&#8217;une maison.\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5956\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5956\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/architectes-de-minorque-confort-et-dintimite\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/architectes-de-minorque-confort-et-dintimite\/\" title=\"Architectes de Minorque. Confort et d&#8217;intimit\u00e9.\" class=\"grid-item-tit-a\" rel=\" \">Architectes de Minorque. Confort et d&#8217;intimit\u00e9.<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 42.769230769231%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/edificio-71-vivinedas-4-Lorenzo-Segui-11-650x278.jpg\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/edificio-71-vivinedas-4-Lorenzo-Segui-11-arnold-standard-thumb-650x278.jpg 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/edificio-71-vivinedas-4-Lorenzo-Segui-11-300x128.jpg 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/edificio-71-vivinedas-4-Lorenzo-Segui-11-1024x438.jpg 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/edificio-71-vivinedas-4-Lorenzo-Segui-11-768x328.jpg 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/edificio-71-vivinedas-4-Lorenzo-Segui-11-1536x657.jpg 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/edificio-71-vivinedas-4-Lorenzo-Segui-11-350x150.jpg 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/edificio-71-vivinedas-4-Lorenzo-Segui-11-arnold-standard-thumb-medium-1000x428.jpg 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/edificio-71-vivinedas-4-Lorenzo-Segui-11.jpg 1836w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Architectes de Minorque. Confort et d&#8217;intimit\u00e9.\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5941\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5941\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/estudio-arquitectura-menorca-4\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/estudio-arquitectura-menorca-4\/\" title=\"Estudio arquitectura Menorca\" class=\"grid-item-tit-a\" rel=\" \">Estudio arquitectura Menorca<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 99.750623441397%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/img_8933-1-1.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/img_8933-1-1.png 401w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/img_8933-1-1-300x300.png 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/img_8933-1-1-150x150.png 150w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/img_8933-1-1-350x349.png 350w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 401px) 100vw, 401px\" alt=\"Estudio arquitectura Menorca\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5957\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5957\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/architectes-de-minorque-lentree-dune-maison-a-minorque\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/architectes-de-minorque-lentree-dune-maison-a-minorque\/\" title=\"Architectes de Minorque. L&#8217;entr\u00e9e d&#8217;une maison \u00e0 Minorque\" class=\"grid-item-tit-a\" rel=\" \">Architectes de Minorque. L&#8217;entr\u00e9e d&#8217;une maison \u00e0 Minorque<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 39.538461538462%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/SEgui-Triay-arquitecte-_Panormica-15-3-5-1-1-1-2-2-2-1-650x257.jpg\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/SEgui-Triay-arquitecte-_Panormica-15-3-5-1-1-1-2-2-2-1-arnold-standard-thumb-650x257.jpg 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/SEgui-Triay-arquitecte-_Panormica-15-3-5-1-1-1-2-2-2-1-300x118.jpg 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/SEgui-Triay-arquitecte-_Panormica-15-3-5-1-1-1-2-2-2-1-1024x404.jpg 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/SEgui-Triay-arquitecte-_Panormica-15-3-5-1-1-1-2-2-2-1-768x303.jpg 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/SEgui-Triay-arquitecte-_Panormica-15-3-5-1-1-1-2-2-2-1-1536x606.jpg 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/SEgui-Triay-arquitecte-_Panormica-15-3-5-1-1-1-2-2-2-1-350x138.jpg 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/SEgui-Triay-arquitecte-_Panormica-15-3-5-1-1-1-2-2-2-1-arnold-standard-thumb-medium-1000x395.jpg 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/SEgui-Triay-arquitecte-_Panormica-15-3-5-1-1-1-2-2-2-1.jpg 1900w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Architectes de Minorque. L&#8217;entr\u00e9e d&#8217;une maison \u00e0 Minorque\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5942\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5942\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/architectes-minorque-architectes-minorque-le-studio-de-larchitecte-llorenc-segui-triay\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/architectes-minorque-architectes-minorque-le-studio-de-larchitecte-llorenc-segui-triay\/\" title=\"Architectes Minorque. Le studio de l&#8217;architecte Lloren\u00e7 Segui Triay\" class=\"grid-item-tit-a\" rel=\" \">Architectes Minorque. Le studio de l&#8217;architecte Lloren\u00e7 Segui Triay<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 74.461538461538%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca-650x484.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca-arnold-standard-thumb-650x484.png 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca-300x224.png 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca-1024x763.png 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca-768x572.png 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca-350x261.png 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca-arnold-standard-thumb-medium-1000x745.png 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca.png 1500w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Architectes Minorque. Le studio de l&#8217;architecte Lloren\u00e7 Segui Triay\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5958\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5958\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/architectes-minorque-loriginalite-et-a-la-discretion\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/architectes-minorque-loriginalite-et-a-la-discretion\/\" title=\"Architectes Minorque. L&#8217;originalit\u00e9 et \u00e0 la discr\u00e9tion\" class=\"grid-item-tit-a\" rel=\" \">Architectes Minorque. L&#8217;originalit\u00e9 et \u00e0 la discr\u00e9tion<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 42.769230769231%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/img_8904_copia-650x278.jpg\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/img_8904_copia-arnold-standard-thumb-650x278.jpg 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/img_8904_copia-300x128.jpg 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/img_8904_copia-1024x438.jpg 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/img_8904_copia-768x329.jpg 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/img_8904_copia-1536x657.jpg 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/img_8904_copia-350x150.jpg 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/img_8904_copia-arnold-standard-thumb-medium-1000x428.jpg 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/img_8904_copia.jpg 1835w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Architectes Minorque. L&#8217;originalit\u00e9 et \u00e0 la discr\u00e9tion\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5943\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5943\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitectos-menorca-la-iluminacion-de-menorca\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitectos-menorca-la-iluminacion-de-menorca\/\" title=\"Arquitectos Menorca. La iluminaci\u00f3n de Menorca\" class=\"grid-item-tit-a\" rel=\" \">Arquitectos Menorca. La iluminaci\u00f3n de Menorca<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 52.615384615385%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/Foto-1-Reforma-casa-Calle-Infanta-Mao-1-6-1-1-1-2-2-2-1-650x342.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/Foto-1-Reforma-casa-Calle-Infanta-Mao-1-6-1-1-1-2-2-2-1-arnold-standard-thumb-650x342.png 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/Foto-1-Reforma-casa-Calle-Infanta-Mao-1-6-1-1-1-2-2-2-1-300x158.png 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/Foto-1-Reforma-casa-Calle-Infanta-Mao-1-6-1-1-1-2-2-2-1-1024x539.png 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/Foto-1-Reforma-casa-Calle-Infanta-Mao-1-6-1-1-1-2-2-2-1-768x404.png 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/Foto-1-Reforma-casa-Calle-Infanta-Mao-1-6-1-1-1-2-2-2-1-1536x808.png 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/Foto-1-Reforma-casa-Calle-Infanta-Mao-1-6-1-1-1-2-2-2-1-350x184.png 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/Foto-1-Reforma-casa-Calle-Infanta-Mao-1-6-1-1-1-2-2-2-1-arnold-standard-thumb-medium-1000x526.png 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/Foto-1-Reforma-casa-Calle-Infanta-Mao-1-6-1-1-1-2-2-2-1.png 1900w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Arquitectos Menorca. La iluminaci\u00f3n de Menorca\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5959\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5959\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/estudio-arquitectura-menorca-los-banos\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/estudio-arquitectura-menorca-los-banos\/\" title=\"Estudio arquitectura Menorca. Los ba\u00f1os.\" class=\"grid-item-tit-a\" rel=\" \">Estudio arquitectura Menorca. Los ba\u00f1os.<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 42.769230769231%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2005\/08\/SEgui-Triay-arquitecte-_Panormica-17-650x278.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2005\/08\/SEgui-Triay-arquitecte-_Panormica-17-arnold-standard-thumb-650x278.png 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2005\/08\/SEgui-Triay-arquitecte-_Panormica-17-300x128.png 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2005\/08\/SEgui-Triay-arquitecte-_Panormica-17-1024x438.png 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2005\/08\/SEgui-Triay-arquitecte-_Panormica-17-768x329.png 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2005\/08\/SEgui-Triay-arquitecte-_Panormica-17-1536x657.png 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2005\/08\/SEgui-Triay-arquitecte-_Panormica-17-350x150.png 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2005\/08\/SEgui-Triay-arquitecte-_Panormica-17-arnold-standard-thumb-medium-1000x428.png 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2005\/08\/SEgui-Triay-arquitecte-_Panormica-17.png 1835w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Estudio arquitectura Menorca. Los ba\u00f1os.\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5944\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5944\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/estudio-arquitectura-menorca-6\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/estudio-arquitectura-menorca-6\/\" title=\"Estudio arquitectura Menorca\" class=\"grid-item-tit-a\" rel=\" \">Estudio arquitectura Menorca<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 42.769230769231%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/Rehabilitacion-fachada-Casa-Vivo-2-650x278.jpg\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/Rehabilitacion-fachada-Casa-Vivo-2-arnold-standard-thumb-650x278.jpg 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/Rehabilitacion-fachada-Casa-Vivo-2-300x128.jpg 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/Rehabilitacion-fachada-Casa-Vivo-2-1024x438.jpg 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/Rehabilitacion-fachada-Casa-Vivo-2-768x329.jpg 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/Rehabilitacion-fachada-Casa-Vivo-2-1536x657.jpg 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/Rehabilitacion-fachada-Casa-Vivo-2-350x150.jpg 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/Rehabilitacion-fachada-Casa-Vivo-2-arnold-standard-thumb-medium-1000x428.jpg 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1980\/08\/Rehabilitacion-fachada-Casa-Vivo-2.jpg 1835w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Estudio arquitectura Menorca\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5960\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5960\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/architectes-de-minorque-larchitecte-llorenc-segui-triay-cree-differentes-zones-dans-la-meme-maison-a-minorque\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/architectes-de-minorque-larchitecte-llorenc-segui-triay-cree-differentes-zones-dans-la-meme-maison-a-minorque\/\" title=\"Architectes de Minorque. L&#8217;architecte Lloren\u00e7 Segui Triay cr\u00e9e diff\u00e9rentes zones dans la m\u00eame maison \u00e0 Minorque\" class=\"grid-item-tit-a\" rel=\" \">Architectes de Minorque. L&#8217;architecte Lloren\u00e7 Segui Triay cr\u00e9e diff\u00e9rentes zones dans la m\u00eame maison \u00e0 Minorque<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 42.769230769231%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/segui-triay-arquitecte-chalet-cala-morell-004-3-1-650x278.jpg\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/segui-triay-arquitecte-chalet-cala-morell-004-3-1-arnold-standard-thumb-650x278.jpg 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/segui-triay-arquitecte-chalet-cala-morell-004-3-1-300x128.jpg 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/segui-triay-arquitecte-chalet-cala-morell-004-3-1-1024x438.jpg 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/segui-triay-arquitecte-chalet-cala-morell-004-3-1-768x328.jpg 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/segui-triay-arquitecte-chalet-cala-morell-004-3-1-1536x657.jpg 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/segui-triay-arquitecte-chalet-cala-morell-004-3-1-350x150.jpg 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/segui-triay-arquitecte-chalet-cala-morell-004-3-1-arnold-standard-thumb-medium-1000x428.jpg 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/segui-triay-arquitecte-chalet-cala-morell-004-3-1.jpg 1836w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Architectes de Minorque. L&#8217;architecte Lloren\u00e7 Segui Triay cr\u00e9e diff\u00e9rentes zones dans la m\u00eame maison \u00e0 Minorque\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5945\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5945\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitectos-de-menorca-la-entrada-de-una-vivienda-en-menorca\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitectos-de-menorca-la-entrada-de-una-vivienda-en-menorca\/\" title=\"Arquitectos de Menorca. La entrada de una vivienda en Menorca\" class=\"grid-item-tit-a\" rel=\" \">Arquitectos de Menorca. La entrada de una vivienda en Menorca<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 76.307692307692%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-9-650x496.jpg\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-9-arnold-standard-thumb-650x496.jpg 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-9-300x229.jpg 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-9-1024x781.jpg 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-9-768x586.jpg 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-9-1536x1171.jpg 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-9-350x267.jpg 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-9-arnold-standard-thumb-medium-1000x763.jpg 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-9.jpg 1900w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Arquitectos de Menorca. La entrada de una vivienda en Menorca\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5961\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5961\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/architectes-minorque-leclairage-de-minorque\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/architectes-minorque-leclairage-de-minorque\/\" title=\"Architectes Minorque. L&#8217;\u00e9clairage de Minorque\" class=\"grid-item-tit-a\" rel=\" \">Architectes Minorque. L&#8217;\u00e9clairage de Minorque<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 39.538461538462%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/SEgui-Triay-arquitecte-_Panormica-19-3-9-650x257.jpg\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/SEgui-Triay-arquitecte-_Panormica-19-3-9-arnold-standard-thumb-650x257.jpg 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/SEgui-Triay-arquitecte-_Panormica-19-3-9-300x118.jpg 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/SEgui-Triay-arquitecte-_Panormica-19-3-9-1024x404.jpg 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/SEgui-Triay-arquitecte-_Panormica-19-3-9-768x303.jpg 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/SEgui-Triay-arquitecte-_Panormica-19-3-9-1536x607.jpg 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/SEgui-Triay-arquitecte-_Panormica-19-3-9-350x138.jpg 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/SEgui-Triay-arquitecte-_Panormica-19-3-9-arnold-standard-thumb-medium-1000x395.jpg 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/SEgui-Triay-arquitecte-_Panormica-19-3-9.jpg 1899w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Architectes Minorque. L&#8217;\u00e9clairage de Minorque\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5946\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5946\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitectos-menorca-la-originalidad-en-la-discrecion\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitectos-menorca-la-originalidad-en-la-discrecion\/\" title=\"Arquitectos Menorca. La originalidad en la discreci\u00f3n.\" class=\"grid-item-tit-a\" rel=\" \">Arquitectos Menorca. La originalidad en la discreci\u00f3n.<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 42.769230769231%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/29-adosados-1-650x278.jpg\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/29-adosados-1-arnold-standard-thumb-650x278.jpg 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/29-adosados-1-300x128.jpg 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/29-adosados-1-1024x438.jpg 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/29-adosados-1-768x328.jpg 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/29-adosados-1-1536x657.jpg 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/29-adosados-1-350x150.jpg 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/29-adosados-1-arnold-standard-thumb-medium-1000x428.jpg 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/29-adosados-1.jpg 1836w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Arquitectos Menorca. La originalidad en la discreci\u00f3n.\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5962\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5962\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/ctes-de-minorque-letude-de-larchitecte-llorenc-segui-triay\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/ctes-de-minorque-letude-de-larchitecte-llorenc-segui-triay\/\" title=\"Architectes de Minorque. L&#8217;\u00e9tude de l&#8217;architecte Lloren\u00e7 Segui Triay\" class=\"grid-item-tit-a\" rel=\" \">Architectes de Minorque. L&#8217;\u00e9tude de l&#8217;architecte Lloren\u00e7 Segui Triay<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 76.307692307692%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-9-650x496.jpg\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-9-arnold-standard-thumb-650x496.jpg 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-9-300x229.jpg 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-9-1024x781.jpg 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-9-768x586.jpg 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-9-1536x1171.jpg 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-9-350x267.jpg 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-9-arnold-standard-thumb-medium-1000x763.jpg 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-9.jpg 1900w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Architectes de Minorque. L&#8217;\u00e9tude de l&#8217;architecte Lloren\u00e7 Segui Triay\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5947\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5947\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/architectes-minorque-la-rehabilitation-dune-maison-a-minorque\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/architectes-minorque-la-rehabilitation-dune-maison-a-minorque\/\" title=\"Architectes Minorque. La r\u00e9habilitation d&#8217;une maison \u00e0 Minorque\" class=\"grid-item-tit-a\" rel=\" \">Architectes Minorque. La r\u00e9habilitation d&#8217;une maison \u00e0 Minorque<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 42.769230769231%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2005\/08\/SEgui-Triay-arquitecte-_Panormica-16-650x278.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2005\/08\/SEgui-Triay-arquitecte-_Panormica-16-arnold-standard-thumb-650x278.png 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2005\/08\/SEgui-Triay-arquitecte-_Panormica-16-300x128.png 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2005\/08\/SEgui-Triay-arquitecte-_Panormica-16-1024x438.png 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2005\/08\/SEgui-Triay-arquitecte-_Panormica-16-768x329.png 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2005\/08\/SEgui-Triay-arquitecte-_Panormica-16-1536x657.png 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2005\/08\/SEgui-Triay-arquitecte-_Panormica-16-350x150.png 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2005\/08\/SEgui-Triay-arquitecte-_Panormica-16-arnold-standard-thumb-medium-1000x428.png 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2005\/08\/SEgui-Triay-arquitecte-_Panormica-16.png 1835w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Architectes Minorque. La r\u00e9habilitation d&#8217;une maison \u00e0 Minorque\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5963\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5963\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/atelier-darchitecture-de-minorque\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/atelier-darchitecture-de-minorque\/\" title=\"Atelier d&#8217;architecture de Minorque\" class=\"grid-item-tit-a\" rel=\" \">Atelier d&#8217;architecture de Minorque<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 42.769230769231%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/web-2-650x278.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/web-2-arnold-standard-thumb-650x278.png 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/web-2-300x128.png 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/web-2-1024x438.png 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/web-2-768x329.png 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/web-2-1536x657.png 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/web-2-350x150.png 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/web-2-arnold-standard-thumb-medium-1000x428.png 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/web-2.png 1834w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Atelier d&#8217;architecture de Minorque\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5948\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5948\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/atelier-darchitecture-de-minorque-2\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/atelier-darchitecture-de-minorque-2\/\" title=\"Atelier d&#8217;architecture de Minorque\" class=\"grid-item-tit-a\" rel=\" \">Atelier d&#8217;architecture de Minorque<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 42.769230769231%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/segui-triay-arquitecte-chalet-cala-morell-004-2-1-650x278.jpg\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/segui-triay-arquitecte-chalet-cala-morell-004-2-1-arnold-standard-thumb-650x278.jpg 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/segui-triay-arquitecte-chalet-cala-morell-004-2-1-300x128.jpg 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/segui-triay-arquitecte-chalet-cala-morell-004-2-1-1024x438.jpg 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/segui-triay-arquitecte-chalet-cala-morell-004-2-1-768x328.jpg 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/segui-triay-arquitecte-chalet-cala-morell-004-2-1-1536x657.jpg 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/segui-triay-arquitecte-chalet-cala-morell-004-2-1-350x150.jpg 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/segui-triay-arquitecte-chalet-cala-morell-004-2-1-arnold-standard-thumb-medium-1000x428.jpg 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/segui-triay-arquitecte-chalet-cala-morell-004-2-1.jpg 1836w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Atelier d&#8217;architecture de Minorque\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5964\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5964\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/atelier-darchitecture-de-minorque-3\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/atelier-darchitecture-de-minorque-3\/\" title=\"Atelier d&#8217;architecture de Minorque\" class=\"grid-item-tit-a\" rel=\" \">Atelier d&#8217;architecture de Minorque<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 35.384615384615%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Concurso-36-viv-Can-Ribes-Mallorca-scaled-2-1-1-1-650x230.jpg\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Concurso-36-viv-Can-Ribes-Mallorca-scaled-2-1-1-1-arnold-standard-thumb-650x230.jpg 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Concurso-36-viv-Can-Ribes-Mallorca-scaled-2-1-1-1-300x106.jpg 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Concurso-36-viv-Can-Ribes-Mallorca-scaled-2-1-1-1-1024x362.jpg 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Concurso-36-viv-Can-Ribes-Mallorca-scaled-2-1-1-1-768x271.jpg 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Concurso-36-viv-Can-Ribes-Mallorca-scaled-2-1-1-1-1536x542.jpg 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Concurso-36-viv-Can-Ribes-Mallorca-scaled-2-1-1-1-2048x723.jpg 2048w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Concurso-36-viv-Can-Ribes-Mallorca-scaled-2-1-1-1-350x124.jpg 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Concurso-36-viv-Can-Ribes-Mallorca-scaled-2-1-1-1-arnold-standard-thumb-medium-1000x353.jpg 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Concurso-36-viv-Can-Ribes-Mallorca-scaled-2-1-1-1-arnold-standard-thumb-big-2000x706.jpg 2000w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Atelier d&#8217;architecture de Minorque\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5949\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5949\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitectos-de-menorca-5\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitectos-de-menorca-5\/\" title=\"Arquitectos de Menorca\" class=\"grid-item-tit-a\" rel=\" \">Arquitectos de Menorca<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 99.750623441397%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/fotos-ed-san-sebastia-005-1-1.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/fotos-ed-san-sebastia-005-1-1.png 401w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/fotos-ed-san-sebastia-005-1-1-300x300.png 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/fotos-ed-san-sebastia-005-1-1-150x150.png 150w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/fotos-ed-san-sebastia-005-1-1-350x349.png 350w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 401px) 100vw, 401px\" alt=\"Arquitectos de Menorca\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5965\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5965\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitectos-menorca\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitectos-menorca\/\" title=\"Arquitectos Menorca\" class=\"grid-item-tit-a\" rel=\" \">Arquitectos Menorca<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 99.750623441397%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/img_5523_2-1-1.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/img_5523_2-1-1.png 401w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/img_5523_2-1-1-300x300.png 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/img_5523_2-1-1-150x150.png 150w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/img_5523_2-1-1-350x349.png 350w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 401px) 100vw, 401px\" alt=\"Arquitectos Menorca\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5950\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5950\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitectos-menorca-4\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitectos-menorca-4\/\" title=\"Arquitectos Menorca\" class=\"grid-item-tit-a\" rel=\" \">Arquitectos Menorca<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 99.750623441397%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/24-vivendes3-copia-1.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/24-vivendes3-copia-1.png 401w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/24-vivendes3-copia-1-300x300.png 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/24-vivendes3-copia-1-150x150.png 150w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/24-vivendes3-copia-1-350x349.png 350w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 401px) 100vw, 401px\" alt=\"Arquitectos Menorca\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5966\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5966\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/atelier-darchitecture-de-minorque-4\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/atelier-darchitecture-de-minorque-4\/\" title=\"Atelier d&#8217;architecture de Minorque\" class=\"grid-item-tit-a\" rel=\" \">Atelier d&#8217;architecture de Minorque<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 42.769230769231%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/bloque-c-002-650x278.jpg\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/bloque-c-002-arnold-standard-thumb-650x278.jpg 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/bloque-c-002-300x128.jpg 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/bloque-c-002-1024x438.jpg 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/bloque-c-002-768x328.jpg 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/bloque-c-002-1536x657.jpg 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/bloque-c-002-350x150.jpg 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/bloque-c-002-arnold-standard-thumb-medium-1000x428.jpg 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/bloque-c-002.jpg 1836w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Atelier d&#8217;architecture de Minorque\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5951\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5951\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/atelier-darchitecture-de-minorque-5\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/atelier-darchitecture-de-minorque-5\/\" title=\"Atelier d&#8217;architecture de Minorque\" class=\"grid-item-tit-a\" rel=\" \">Atelier d&#8217;architecture de Minorque<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 42.769230769231%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/3134-21-650x278.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/3134-21-arnold-standard-thumb-650x278.png 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/3134-21-300x128.png 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/3134-21-1024x438.png 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/3134-21-768x329.png 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/3134-21-1536x657.png 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/3134-21-350x150.png 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/3134-21-arnold-standard-thumb-medium-1000x428.png 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/3134-21.png 1834w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Atelier d&#8217;architecture de Minorque\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5967\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5967\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/atelier-darchitecture-de-minorque-7\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/atelier-darchitecture-de-minorque-7\/\" title=\"Atelier d&#8217;architecture de Minorque\" class=\"grid-item-tit-a\" rel=\" \">Atelier d&#8217;architecture de Minorque<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 42.769230769231%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/3134-47-650x278.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/3134-47-arnold-standard-thumb-650x278.png 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/3134-47-300x128.png 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/3134-47-1024x438.png 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/3134-47-768x329.png 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/3134-47-1536x657.png 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/3134-47-350x150.png 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/3134-47-arnold-standard-thumb-medium-1000x428.png 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/3134-47.png 1834w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Atelier d&#8217;architecture de Minorque\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5952\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5952\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitectos-de-menorca\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitectos-de-menorca\/\" title=\"Arquitectos de Menorca. Dise\u00f1ar una vivienda en Menorca. Las necesidades.\" class=\"grid-item-tit-a\" rel=\" \">Arquitectos de Menorca. Dise\u00f1ar una vivienda en Menorca. Las necesidades.<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 108.69565217391%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1998\/08\/Foto-1-Vivienda-Rafa-y-Raquel-1.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1998\/08\/Foto-1-Vivienda-Rafa-y-Raquel-1.png 368w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1998\/08\/Foto-1-Vivienda-Rafa-y-Raquel-1-276x300.png 276w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1998\/08\/Foto-1-Vivienda-Rafa-y-Raquel-1-350x380.png 350w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 368px) 100vw, 368px\" alt=\"Arquitectos de Menorca. Dise\u00f1ar una vivienda en Menorca. Las necesidades.\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5968\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5968\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitectos-de-menorca-2\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitectos-de-menorca-2\/\" title=\"Arquitectos de Menorca\" class=\"grid-item-tit-a\" rel=\" \">Arquitectos de Menorca<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 75.846153846154%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-2-Hotel-Artemisia.-lorenzo-segui-Triay.-Menorca-650x493.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-2-Hotel-Artemisia.-lorenzo-segui-Triay.-Menorca-arnold-standard-thumb-650x493.png 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-2-Hotel-Artemisia.-lorenzo-segui-Triay.-Menorca-300x228.png 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-2-Hotel-Artemisia.-lorenzo-segui-Triay.-Menorca-1024x777.png 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-2-Hotel-Artemisia.-lorenzo-segui-Triay.-Menorca-768x583.png 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-2-Hotel-Artemisia.-lorenzo-segui-Triay.-Menorca-350x266.png 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-2-Hotel-Artemisia.-lorenzo-segui-Triay.-Menorca-arnold-standard-thumb-medium-1000x759.png 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-2-Hotel-Artemisia.-lorenzo-segui-Triay.-Menorca.png 1500w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Arquitectos de Menorca\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5953\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5953\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitectos-de-menorca-4\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/arquitectos-de-menorca-4\/\" title=\"Arquitectos de Menorca. Una rehabilitaci\u00f3n en Menorca.\" class=\"grid-item-tit-a\" rel=\" \">Arquitectos de Menorca. Una rehabilitaci\u00f3n en Menorca.<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 99.750623441397%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/1-9-1.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/1-9-1.png 401w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/1-9-1-300x300.png 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/1-9-1-150x150.png 150w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/1-9-1-350x349.png 350w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 401px) 100vw, 401px\" alt=\"Arquitectos de Menorca. Una rehabilitaci\u00f3n en Menorca.\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5969\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5969\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/estudio-arquitectura-menorca-un-proyecto-integral\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/estudio-arquitectura-menorca-un-proyecto-integral\/\" title=\"Estudio arquitectura Menorca. Un proyecto integral.\" class=\"grid-item-tit-a\" rel=\" \">Estudio arquitectura Menorca. Un proyecto integral.<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 99.800399201597%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/segui-triay-arquitecte-chalet-cala-morell-004-1-1.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/segui-triay-arquitecte-chalet-cala-morell-004-1-1.png 501w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/segui-triay-arquitecte-chalet-cala-morell-004-1-1-300x300.png 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/segui-triay-arquitecte-chalet-cala-morell-004-1-1-150x150.png 150w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/segui-triay-arquitecte-chalet-cala-morell-004-1-1-350x349.png 350w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 501px) 100vw, 501px\" alt=\"Estudio arquitectura Menorca. Un proyecto integral.\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5954\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5954\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/estudio-arquitectura-menorca\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/estudio-arquitectura-menorca\/\" title=\"Estudio arquitectura Menorca. Rehabilitar una vivienda en Menorca.\" class=\"grid-item-tit-a\" rel=\" \">Estudio arquitectura Menorca. Rehabilitar una vivienda en Menorca.<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 99.750623441397%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/edificio-22-viviendas-web-1.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/edificio-22-viviendas-web-1.png 401w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/edificio-22-viviendas-web-1-300x300.png 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/edificio-22-viviendas-web-1-150x150.png 150w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/edificio-22-viviendas-web-1-350x349.png 350w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 401px) 100vw, 401px\" alt=\"Estudio arquitectura Menorca. Rehabilitar una vivienda en Menorca.\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5970\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5970\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/estudio-arquitectura-menorca-3\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/estudio-arquitectura-menorca-3\/\" title=\"Estudio arquitectura Menorca\" class=\"grid-item-tit-a\" rel=\" \">Estudio arquitectura Menorca<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">ao\u00fbt 5, 2024<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 39.538461538462%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/Foto-1-Vivienda-Rafa-y-Raquel-1-1-9-650x257.jpg\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/Foto-1-Vivienda-Rafa-y-Raquel-1-1-9-arnold-standard-thumb-650x257.jpg 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/Foto-1-Vivienda-Rafa-y-Raquel-1-1-9-300x118.jpg 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/Foto-1-Vivienda-Rafa-y-Raquel-1-1-9-1024x404.jpg 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/Foto-1-Vivienda-Rafa-y-Raquel-1-1-9-768x303.jpg 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/Foto-1-Vivienda-Rafa-y-Raquel-1-1-9-1536x606.jpg 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/Foto-1-Vivienda-Rafa-y-Raquel-1-1-9-350x138.jpg 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/Foto-1-Vivienda-Rafa-y-Raquel-1-1-9-arnold-standard-thumb-medium-1000x395.jpg 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/1999\/08\/Foto-1-Vivienda-Rafa-y-Raquel-1-1-9.jpg 1900w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Estudio arquitectura Menorca\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5895\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5895\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/visite-nuestro-estudio-en-la-calle-arravaleta-13-a1o-en-mao-menorca\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/visite-nuestro-estudio-en-la-calle-arravaleta-13-a1o-en-mao-menorca\/\" title=\"Visite nuestro estudio en la calle Arravaleta 13-A1\u00ba en Ma\u00f3 Menorca\" class=\"grid-item-tit-a\" rel=\" \">Visite nuestro estudio en la calle Arravaleta 13-A1\u00ba en Ma\u00f3 Menorca<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">juillet 12, 2023<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 75.076923076923%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-1-650x488.jpg\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-1-arnold-standard-thumb-650x488.jpg 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-1-300x225.jpg 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-1-1024x768.jpg 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-1-768x576.jpg 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-1-1536x1152.jpg 1536w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-1-350x263.jpg 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-1-arnold-thumb-43-medium-1000x750.jpg 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/07\/Despacho-1.jpg 1900w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Visite nuestro estudio en la calle Arravaleta 13-A1\u00ba en Ma\u00f3 Menorca\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5873\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5873\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/rehabilitacion-fachada-del-palacio-vivo-truyos-de-ciutadella\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/rehabilitacion-fachada-del-palacio-vivo-truyos-de-ciutadella\/\" title=\"Rehabilitaci\u00f3n de la fachada del Palacio Viv\u00f3 Truyos de Ciutadella\" class=\"grid-item-tit-a\" rel=\" \">Rehabilitaci\u00f3n de la fachada del Palacio Viv\u00f3 Truyos de Ciutadella<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">juin 19, 2023<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 122.30769230769%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Rehabilitacion-fachada-Casa-Vivo.-LORENZO-SEGUI-TRIAY11-650x795.jpg\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Rehabilitacion-fachada-Casa-Vivo.-LORENZO-SEGUI-TRIAY11-arnold-standard-thumb-650x795.jpg 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Rehabilitacion-fachada-Casa-Vivo.-LORENZO-SEGUI-TRIAY11-245x300.jpg 245w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Rehabilitacion-fachada-Casa-Vivo.-LORENZO-SEGUI-TRIAY11-768x939.jpg 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Rehabilitacion-fachada-Casa-Vivo.-LORENZO-SEGUI-TRIAY11-350x428.jpg 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Rehabilitacion-fachada-Casa-Vivo.-LORENZO-SEGUI-TRIAY11.jpg 784w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Rehabilitaci\u00f3n de la fachada del Palacio Viv\u00f3 Truyos de Ciutadella\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5356\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5356\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/concurso-36-viv-can-ribes-mallorca-lorenzo-segui-triay-menorca\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/concurso-36-viv-can-ribes-mallorca-lorenzo-segui-triay-menorca\/\" title=\"Concurso 36 viv Can Ribes Mallorca. lorenzo segui Triay. Menorca\" class=\"grid-item-tit-a\" rel=\" \">Concurso 36 viv Can Ribes Mallorca. lorenzo segui Triay. Menorca<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">juin 6, 2023<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 35.230769230769%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Concurso-36-viv-Can-Ribes-Mallorca.-lorenzo-segui-Triay.-Menorca-650x229.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Concurso-36-viv-Can-Ribes-Mallorca.-lorenzo-segui-Triay.-Menorca-arnold-standard-thumb-650x229.png 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Concurso-36-viv-Can-Ribes-Mallorca.-lorenzo-segui-Triay.-Menorca-300x106.png 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Concurso-36-viv-Can-Ribes-Mallorca.-lorenzo-segui-Triay.-Menorca-1024x361.png 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Concurso-36-viv-Can-Ribes-Mallorca.-lorenzo-segui-Triay.-Menorca-768x271.png 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Concurso-36-viv-Can-Ribes-Mallorca.-lorenzo-segui-Triay.-Menorca-350x123.png 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Concurso-36-viv-Can-Ribes-Mallorca.-lorenzo-segui-Triay.-Menorca-arnold-standard-thumb-medium-1000x353.png 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Concurso-36-viv-Can-Ribes-Mallorca.-lorenzo-segui-Triay.-Menorca.png 1500w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Concurso 36 viv Can Ribes Mallorca. lorenzo segui Triay. Menorca\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5377\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5377\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/reforma-casa-calle-alayor-lorenzo-segui-triay-menorca\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/reforma-casa-calle-alayor-lorenzo-segui-triay-menorca\/\" title=\"Reforma casa Calle Alayor. Lorenzo Segui Triay. Menorca\" class=\"grid-item-tit-a\" rel=\" \">Reforma casa Calle Alayor. Lorenzo Segui Triay. Menorca<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">juin 6, 2023<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 74.461538461538%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca-650x484.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca-arnold-standard-thumb-650x484.png 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca-300x224.png 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca-1024x763.png 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca-768x572.png 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca-350x261.png 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca-arnold-standard-thumb-medium-1000x745.png 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Alayor.-lorenzo-segui-Triay.-Menorca.png 1500w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Reforma casa Calle Alayor. Lorenzo Segui Triay. Menorca\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5381\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5381\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/reforma-casa-calle-infanta-mao-lorenzo-segui-triay-menorca\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/reforma-casa-calle-infanta-mao-lorenzo-segui-triay-menorca\/\" title=\"Reforma casa Calle Infanta Ma\u00f3. Lorenzo Segui Triay. Menorca\" class=\"grid-item-tit-a\" rel=\" \">Reforma casa Calle Infanta Ma\u00f3. Lorenzo Segui Triay. Menorca<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">juin 6, 2023<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 129.53846153846%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Infanta-Mao.-lorenzo-segui-Triay.-Menorca-650x842.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Infanta-Mao.-lorenzo-segui-Triay.-Menorca-arnold-standard-thumb-650x842.png 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Infanta-Mao.-lorenzo-segui-Triay.-Menorca-232x300.png 232w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Infanta-Mao.-lorenzo-segui-Triay.-Menorca-791x1024.png 791w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Infanta-Mao.-lorenzo-segui-Triay.-Menorca-768x994.png 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Infanta-Mao.-lorenzo-segui-Triay.-Menorca-1186x1536.png 1186w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Infanta-Mao.-lorenzo-segui-Triay.-Menorca-350x453.png 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Infanta-Mao.-lorenzo-segui-Triay.-Menorca-arnold-standard-thumb-medium-1000x1295.png 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-casa-Calle-Infanta-Mao.-lorenzo-segui-Triay.-Menorca.png 1500w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Reforma casa Calle Infanta Ma\u00f3. Lorenzo Segui Triay. Menorca\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5397\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5397\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/reforma-casa-julie-catala-lorenzo-segui-triay-menorca\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/reforma-casa-julie-catala-lorenzo-segui-triay-menorca\/\" title=\"Reforma Casa Julie Catal\u00e0.  Lorenzo Segui Triay. Menorca\" class=\"grid-item-tit-a\" rel=\" \">Reforma Casa Julie Catal\u00e0.  Lorenzo Segui Triay. Menorca<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">juin 6, 2023<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 75.076923076923%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-Casa-Julie-Catala.-lorenzo-segui-Triay.-Menorca-650x488.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-Casa-Julie-Catala.-lorenzo-segui-Triay.-Menorca-arnold-standard-thumb-650x488.png 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-Casa-Julie-Catala.-lorenzo-segui-Triay.-Menorca-300x225.png 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-Casa-Julie-Catala.-lorenzo-segui-Triay.-Menorca-1024x768.png 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-Casa-Julie-Catala.-lorenzo-segui-Triay.-Menorca-768x576.png 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-Casa-Julie-Catala.-lorenzo-segui-Triay.-Menorca-350x263.png 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-Casa-Julie-Catala.-lorenzo-segui-Triay.-Menorca-arnold-thumb-43-medium-1000x750.png 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-1-Reforma-Casa-Julie-Catala.-lorenzo-segui-Triay.-Menorca.png 1500w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Reforma Casa Julie Catal\u00e0.  Lorenzo Segui Triay. Menorca\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5401\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5401\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/hotel-artemisia-lorenzo-segui-triay-menorca\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/hotel-artemisia-lorenzo-segui-triay-menorca\/\" title=\"Hotel Artemisia. Lorenzo Segui Triay. Menorca\" class=\"grid-item-tit-a\" rel=\" \">Hotel Artemisia. Lorenzo Segui Triay. Menorca<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">juin 6, 2023<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 75.846153846154%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-2-Hotel-Artemisia.-lorenzo-segui-Triay.-Menorca-650x493.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-2-Hotel-Artemisia.-lorenzo-segui-Triay.-Menorca-arnold-standard-thumb-650x493.png 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-2-Hotel-Artemisia.-lorenzo-segui-Triay.-Menorca-300x228.png 300w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-2-Hotel-Artemisia.-lorenzo-segui-Triay.-Menorca-1024x777.png 1024w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-2-Hotel-Artemisia.-lorenzo-segui-Triay.-Menorca-768x583.png 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-2-Hotel-Artemisia.-lorenzo-segui-Triay.-Menorca-350x266.png 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-2-Hotel-Artemisia.-lorenzo-segui-Triay.-Menorca-arnold-standard-thumb-medium-1000x759.png 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-2-Hotel-Artemisia.-lorenzo-segui-Triay.-Menorca.png 1500w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Hotel Artemisia. Lorenzo Segui Triay. Menorca\"><\/div><\/div><\/section><section class=\"grid-item sea-grid-item filter_news\" data-postid=\"5405\"><div class=\"grid-item-inside bm-touch-tab\" ><div class=\"grid-item-con sea-grid-item-con   post--5405\" ><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/unifamiliar-lorenzo-segui-triay\/\"   class=\"grid-item-mask-link\"><\/a><div class=\"grid-item-con-text\"><h2 class=\"grid-item-tit\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/unifamiliar-lorenzo-segui-triay\/\" title=\"Unifamiliar al passeig maritim de Cuidadela. Lorenzo Segu\u00ed Triay\" class=\"grid-item-tit-a\" rel=\" \">Unifamiliar al passeig maritim de Cuidadela. Lorenzo Segu\u00ed Triay<\/a><\/h2><span class=\"grid-item-cate\"><a href=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/category\/news\/\" title=\"View all posts in News\" class=\"grid-item-cate-a\">News<\/a><\/span><div class=\"grid-item-date\">juin 6, 2023<\/div><\/div><\/div><div class=\"brick-content ux-lazyload-wrap\" style=\" padding-top: 151.53846153846%;\"><img class=\"grid-item-img ux-background-img-1st lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-UNIFAMILIAR.-LORENZO-SEGUI-TRIAY-650x985.png\" data-srcset=\"https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-UNIFAMILIAR.-LORENZO-SEGUI-TRIAY-arnold-standard-thumb-650x985.png 650w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-UNIFAMILIAR.-LORENZO-SEGUI-TRIAY-198x300.png 198w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-UNIFAMILIAR.-LORENZO-SEGUI-TRIAY-676x1024.png 676w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-UNIFAMILIAR.-LORENZO-SEGUI-TRIAY-768x1164.png 768w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-UNIFAMILIAR.-LORENZO-SEGUI-TRIAY-1014x1536.png 1014w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-UNIFAMILIAR.-LORENZO-SEGUI-TRIAY-1352x2048.png 1352w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-UNIFAMILIAR.-LORENZO-SEGUI-TRIAY-350x530.png 350w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-UNIFAMILIAR.-LORENZO-SEGUI-TRIAY-arnold-standard-thumb-medium-1000x1515.png 1000w, https:\/\/xn--llorenseguiarquitecte-63b.com\/wp-content\/uploads\/2023\/06\/Foto-UNIFAMILIAR.-LORENZO-SEGUI-TRIAY.png 1500w\" data-sizes=\"(max-width: 480px) 320px,(max-width: 767px) 500px,(max-width: 650px) 100vw, 650px\" alt=\"Unifamiliar al passeig maritim de Cuidadela. Lorenzo Segu\u00ed Triay\"><\/div><\/div><\/section><\/div><\/div><\/div><\/div><\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>ARQUITECTO MENORCA. Dise\u00f1o de viviendas unifamiliares en Menorca.Newsjuin 12, 2025ARQUITECTO &hellip;<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/wp-json\/wp\/v2\/pages\/26"}],"collection":[{"href":"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/wp-json\/wp\/v2\/comments?post=26"}],"version-history":[{"count":17,"href":"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/wp-json\/wp\/v2\/pages\/26\/revisions"}],"predecessor-version":[{"id":6565,"href":"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/wp-json\/wp\/v2\/pages\/26\/revisions\/6565"}],"wp:attachment":[{"href":"https:\/\/xn--llorenseguiarquitecte-63b.com\/fr\/wp-json\/wp\/v2\/media?parent=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}